{"id":59855,"date":"2021-11-02T04:24:09","date_gmt":"2021-11-02T04:24:09","guid":{"rendered":"https:\/\/blog.newage.com\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/"},"modified":"2021-11-02T16:32:00","modified_gmt":"2021-11-02T16:32:00","slug":"newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021","status":"publish","type":"post","link":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/","title":{"rendered":"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ganar no es f\u00e1cil, a menos que se sea parte de NewAge, claro est\u00e1. <\/p>\n\n<p class=\"wp-block-paragraph\">Desde nuestros inicios en 2016, hemos sido galardonados con una cantidad <strong>impresionante<\/strong> de premios \u2014<strong>m\u00e1s de 400<\/strong>, si deseamos contarlos\u2014 en una amplia variedad de competencias tanto nacionales como internacionales.  Para algunos, eso ser\u00eda m\u00e1s que suficiente para sentarse, relajarse y cerrar el d\u00eda.  Pero no para nosotros.  Y nos llena de emoci\u00f3n decir que tenemos la intenci\u00f3n de poner todav\u00eda m\u00e1s premios en nuestra vitrina. <\/p>\n\n<p class=\"wp-block-paragraph\">Este a\u00f1o, en la sexta edici\u00f3n de los premios <a href=\"https:\/\/globeeawards.com\/american-business-awards\/\">American Best in Business Awards<\/a>, NewAge tuvo un papel <strong>IMPRESIONANTE<\/strong>, pues no solo fue distinguida como Gran Ganadora del Globee\u00ae Award, tambi\u00e9n fue seleccionada como <strong>Compa\u00f1\u00eda del A\u00f1o<\/strong> y como la <strong>Compa\u00f1\u00eda del A\u00f1o M\u00e1s Innovadora<\/strong>, \u00a1entre varias distinciones m\u00e1s!<\/p>\n\n<p class=\"wp-block-paragraph\">Los American Best in Business Awards, parte del programa de premios Globee Awards, es el programa de reconocimiento m\u00e1s importante cuyo objetivo es premiar a las empresas y profesionales m\u00e1s destacados de Estados Unidos en cada industria.  Disponible para las organizaciones con al menos una oficina en Estados Unidos, organizaciones de todos tama\u00f1os \u2014startups, organizaciones gubernamentales, p\u00fablicas y privadas, con o sin fines de lucro\u2014 son elegibles para enviar sus nominaciones para los American Best in Business Awards y competir en una amplia gama de categor\u00edas en la que se premian los logros obtenidos en cada aspecto de los negocios.  M\u00e1s de 35 jueces expertos, pertenecientes a una amplia gama de industrias, participaron en el proceso de calificaci\u00f3n. <\/p>\n\n<p class=\"wp-block-paragraph\">Haber resultado Gran Ganadora del Globee Award nos posiciona en un nivel aparte; significa que NewAge es <strong>una de tan solo 10 compa\u00f1\u00edas<\/strong>, entre cientos de miles de postulaciones, que recibe este reconocimiento gracias a los importantes logros obtenidos a lo largo del pasado a\u00f1o.  NewAge comparte este codiciado honor con <a href=\"https:\/\/www.ibm.com\/us-en?p1=Search&amp;p4=43700050478421002&amp;p5=e&amp;gclsrc=aw.ds&amp;gclid=EAIaIQobChMI7vXw3JD68QIVDm1vBB3KXw-JEAAYASAAEgIZnPD_BwE\">IBM<\/a>, <a href=\"https:\/\/www.wolterskluwer.com\/en\">Wolters Kluwer<\/a> y con otras notables organizaciones. <\/p>\n\n<p class=\"wp-block-paragraph\">Y no solo NewAge result\u00f3 premiada, Brent Willis, su CEO, fue reconocido como <strong>Business Maverick of the Year<\/strong>. Todas estas distinciones muestran que lo significa ser una empresa guiada por prop\u00f3sitos que tiene como objetivo cambiar el mundo.&#13;\n<br\/><br\/><a href=\"https:\/\/www.globenewswire.com\/news-release\/2021\/10\/19\/2316257\/0\/en\/NewAge-Recognized-as-Grand-Winner-in-the-2021-American-Best-in-Business-Awards.html\" target=\"_blank\" rel=\"noreferrer noopener\">Lee m\u00e1s aqu\u00ed<\/a> acerca de nuestros notables logros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ganar no es f\u00e1cil, a menos que se sea parte de NewAge, claro est\u00e1. Desde nuestros inicios en 2016, hemos sido galardonados con una cantidad impresionante de premios \u2014m\u00e1s de 400, si deseamos contarlos\u2014 en una amplia variedad de competencias tanto nacionales como internacionales. Para algunos, eso ser\u00eda m\u00e1s que suficiente para sentarse, relajarse y cerrar el d\u00eda. Pero no para nosotros. Y nos llena de emoci\u00f3n decir que tenemos la intenci\u00f3n de poner todav\u00eda m\u00e1s premios en nuestra vitrina. Este a\u00f1o, en la sexta edici\u00f3n de los premios American Best in Business Awards, NewAge tuvo un papel IMPRESIONANTE, pues no solo fue distinguida como Gran Ganadora del Globee\u00ae Award, tambi\u00e9n fue seleccionada como Compa\u00f1\u00eda del A\u00f1o y como la Compa\u00f1\u00eda del A\u00f1o M\u00e1s Innovadora, \u00a1entre varias distinciones m\u00e1s! Los American Best in Business Awards, parte del programa de premios Globee Awards, es el programa de reconocimiento m\u00e1s importante cuyo objetivo es premiar a las empresas y profesionales m\u00e1s destacados de Estados Unidos en cada industria. Disponible para las organizaciones con al menos una oficina en Estados Unidos, organizaciones de todos tama\u00f1os \u2014startups, organizaciones gubernamentales, p\u00fablicas y privadas, con o sin fines de lucro\u2014 son elegibles para enviar sus nominaciones [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":59856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1240],"tags":[],"class_list":["post-59855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-business"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NewAge | Blog \u2014 NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.<\/title>\n<meta name=\"description\" content=\"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021\" \/>\n<meta property=\"og:description\" content=\"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Partner.Co\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T04:24:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T16:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"courtney senecal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.\" \/>\n<meta name=\"twitter:description\" content=\"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"courtney senecal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/\"},\"author\":{\"name\":\"courtney senecal\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#\\\/schema\\\/person\\\/96cafa11d5671bfdcf4b0cb89271de80\"},\"headline\":\"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.\",\"datePublished\":\"2021-11-02T04:24:09+00:00\",\"dateModified\":\"2021-11-02T16:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/\"},\"wordCount\":393,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg\",\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/\",\"url\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/\",\"name\":\"NewAge | Blog \u2014 NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg\",\"datePublished\":\"2021-11-02T04:24:09+00:00\",\"dateModified\":\"2021-11-02T16:32:00+00:00\",\"description\":\"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg\",\"width\":1400,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#website\",\"url\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/\",\"name\":\"Partner.Co\",\"description\":\"Journal\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#organization\",\"name\":\"PartnerCo\",\"url\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/ptr_logo-primary-green_200px.png\",\"contentUrl\":\"https:\\\/\\\/blog.partner.co\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/ptr_logo-primary-green_200px.png\",\"width\":200,\"height\":33,\"caption\":\"PartnerCo\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/#\\\/schema\\\/person\\\/96cafa11d5671bfdcf4b0cb89271de80\",\"name\":\"courtney senecal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g\",\"caption\":\"courtney senecal\"},\"url\":\"https:\\\/\\\/blog.partner.co\\\/es-mx\\\/author\\\/courtney-senecalariix-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NewAge | Blog \u2014 NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.","description":"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/","og_locale":"es_MX","og_type":"article","og_title":"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021","og_description":"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.","og_url":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/","og_site_name":"Partner.Co","article_published_time":"2021-11-02T04:24:09+00:00","article_modified_time":"2021-11-02T16:32:00+00:00","og_image":[{"width":1400,"height":800,"url":"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg","type":"image\/jpeg"}],"author":"courtney senecal","twitter_card":"summary_large_image","twitter_title":"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.","twitter_description":"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.","twitter_misc":{"Escrito por":"courtney senecal","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#article","isPartOf":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/"},"author":{"name":"courtney senecal","@id":"https:\/\/blog.partner.co\/es-mx\/#\/schema\/person\/96cafa11d5671bfdcf4b0cb89271de80"},"headline":"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.","datePublished":"2021-11-02T04:24:09+00:00","dateModified":"2021-11-02T16:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/"},"wordCount":393,"publisher":{"@id":"https:\/\/blog.partner.co\/es-mx\/#organization"},"image":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg","articleSection":["Negocios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/","url":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/","name":"NewAge | Blog \u2014 NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021.","isPartOf":{"@id":"https:\/\/blog.partner.co\/es-mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#primaryimage"},"image":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg","datePublished":"2021-11-02T04:24:09+00:00","dateModified":"2021-11-02T16:32:00+00:00","description":"NewAge es galardonada como Globee\u00ae Award Grand Winner (Gran Ganadora del premio Globee) y como Compa\u00f1\u00eda del A\u00f1o, entre otras distinciones, en el marco del programa de premios empresariales m\u00e1s relevante de Estados Unidos.","breadcrumb":{"@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#primaryimage","url":"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg","contentUrl":"https:\/\/blog.partner.co\/wp-content\/uploads\/2021\/10\/NAB_BLOG_best-in-biz_10-2021_USA-ENG_v02.jpg","width":1400,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/blog.partner.co\/es-mx\/newage-logra-una-destacada-participacion-en-los-premios-american-best-in-business-awards-edicion-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.partner.co\/es-mx\/"},{"@type":"ListItem","position":2,"name":"NewAge logra una destacada participaci\u00f3n en los premios American Best in Business Awards, edici\u00f3n 2021."}]},{"@type":"WebSite","@id":"https:\/\/blog.partner.co\/es-mx\/#website","url":"https:\/\/blog.partner.co\/es-mx\/","name":"Partner.Co","description":"Journal","publisher":{"@id":"https:\/\/blog.partner.co\/es-mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.partner.co\/es-mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/blog.partner.co\/es-mx\/#organization","name":"PartnerCo","url":"https:\/\/blog.partner.co\/es-mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.partner.co\/es-mx\/#\/schema\/logo\/image\/","url":"https:\/\/blog.partner.co\/wp-content\/uploads\/2024\/01\/ptr_logo-primary-green_200px.png","contentUrl":"https:\/\/blog.partner.co\/wp-content\/uploads\/2024\/01\/ptr_logo-primary-green_200px.png","width":200,"height":33,"caption":"PartnerCo"},"image":{"@id":"https:\/\/blog.partner.co\/es-mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/blog.partner.co\/es-mx\/#\/schema\/person\/96cafa11d5671bfdcf4b0cb89271de80","name":"courtney senecal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/714c46463fba7d93af4fa6c04b9ab98479f31dfa631f98aa39c2f582a885d0c1?s=96&d=mm&r=g","caption":"courtney senecal"},"url":"https:\/\/blog.partner.co\/es-mx\/author\/courtney-senecalariix-com\/"}]}},"_links":{"self":[{"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/posts\/59855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/comments?post=59855"}],"version-history":[{"count":9,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/posts\/59855\/revisions"}],"predecessor-version":[{"id":59878,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/posts\/59855\/revisions\/59878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/media\/59856"}],"wp:attachment":[{"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/media?parent=59855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/categories?post=59855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.partner.co\/es-mx\/wp-json\/wp\/v2\/tags?post=59855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}